{"id":219,"date":"2025-07-15T10:16:33","date_gmt":"2025-07-15T10:16:33","guid":{"rendered":"https:\/\/www.iltuodiplomaonline.it\/?page_id=219"},"modified":"2025-07-17T11:03:19","modified_gmt":"2025-07-17T11:03:19","slug":"landing-vsl-2","status":"publish","type":"page","link":"http:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/","title":{"rendered":"Landing VSL"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"219\" class=\"elementor elementor-219\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d0985c2 e-flex e-con-boxed e-con e-parent\" data-id=\"5d0985c2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-19624fb e-con-full e-flex e-con e-child\" data-id=\"19624fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f16da3c elementor-widget elementor-widget-image\" data-id=\"7f16da3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"200\" src=\"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png\" class=\"attachment-large size-large wp-image-165\" alt=\"\" srcset=\"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png 600w, http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz-300x100.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f5b6cfd elementor-widget elementor-widget-heading\" data-id=\"5f5b6cfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Senza diploma di maturit\u00e0, sei tagliato fuori\u2026 ma con Excol puoi farcela!\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11ba660b elementor-widget elementor-widget-text-editor\" data-id=\"11ba660b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il tuo Diploma di Stato \u00e8 <span style=\"color: #ffff00;\">a portata di mano<\/span> con Excol<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5983805f elementor-widget elementor-widget-text-editor\" data-id=\"5983805f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con la flessibilit\u00e0 che desideri e la garanzia che meriti, grazie alla formula \u201cPromosso o Ripreparato\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fcc1ffb elementor-hidden-desktop elementor-widget elementor-widget-video\" data-id=\"6fcc1ffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=XHOmBV4js_E&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64816384 e-con-full e-flex e-con e-child\" data-id=\"64816384\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a3552f0 elementor-widget elementor-widget-ucaddon_multi_line_button\" data-id=\"6a3552f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_multi_line_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Multi Line Button -->\n\t\t<link id='font-awesome-css' href='http:\/\/www.iltuodiplomaonline.it\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='http:\/\/www.iltuodiplomaonline.it\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Multi Line Button *\/\n\n#uc_multi_line_button_elementor_6a3552f0 *{\n\tmargin:0;\n\tbox-sizing: border-box;\n}\n\n#uc_multi_line_button_elementor_6a3552f0 .uc_container_holder{\n\tposition:relative;\n\ttext-align:center;\n}\n\n#uc_multi_line_button_elementor_6a3552f0 .uc_container_holder a.uc_multi-line-button{\n  color: white;\n  display: block;\n  text-decoration: none;\n  transition:0.3s;\n  text-align:center;\n }\n\n\n#uc_multi_line_button_elementor_6a3552f0 .uc_container_holder a.uc_multi-line-button .uc_title {\n  \n  display: block;\n}\n\n#uc_multi_line_button_elementor_6a3552f0 .uc_flex\n{\n  display:inline-flex;\n}\n\n.uc_title\n{\n  font-size: 24px;\n}\n\n#uc_multi_line_button_elementor_6a3552f0 .uc_icon\n{\n  line-height:1em;\n  display:flex;\n}\n\n#uc_multi_line_button_elementor_6a3552f0 .uc_icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n<\/style>\n\n<div class=\"uc_multi_line_buttons\" id=\"uc_multi_line_button_elementor_6a3552f0\">\n    \t<div class=\"uc_container_holder\">\n            <a id=\"\" class=\"uc_multi-line-button  elementor-animation-grow\" href=\"\" >\n\t\t\t\t<div class=\"uc_flex\">   \n                  \n                  \n                    \t\n\n                   \n                   \n                   <div>\n                   <div class=\"uc_title\">PARLA&#x20;CON&#x20;UN&#x20;NOSTRO&#x20;TUTOR&#x20;<\/div>\n                     <div class=\"uc_space_between\"><\/div>\n                   <span class=\"uc_subtitle\">Offerta&#x20;valida&#x20;fino&#x20;a&#x20;esaurimento&#x20;posti<\/span>\n                   <\/div>\n                  \n                  \n                  \n                <\/div>\n            <\/a>\n        <\/div>\n    <\/div>\n<!-- end Multi Line Button -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45025454 elementor-widget elementor-widget-text-editor\" data-id=\"45025454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Possibilit\u00e0 di pagamento a rate<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b6f9bd1 e-con-full e-flex e-con e-child\" data-id=\"5b6f9bd1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-545baf70 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-video\" data-id=\"545baf70\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=XHOmBV4js_E&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"unlimited-elements-background-overlay\" data-forid=\"5d0985c2\" data-location=\"back\" style=\"display:none\">\n\t\t\t<template>\n\t\t\t\n<!-- start Smoke Background Effect -->\n<style>\/* widget: Smoke Background Effect *\/\n\n#uc_ue_webgl_fluid_simulation_bg_addon10695 {\n  position:  sticky ;\n  inset: 0;\n  width: 100%;\n  height: 100%;\n  max-height: 100vh;\n  pointer-events: none;\n}\n\n\n\n<\/style>\n\n<canvas id=\"uc_ue_webgl_fluid_simulation_bg_addon10695\"><\/canvas>\n<script type=\"text\/javascript\"  id=\"ue_script_ue_webgl_fluid_simulation\">\n\n\/* Smoke Background Effect scripts: *\/ \n\n( () => {\n  \t\n    const canvas = document.querySelector('#uc_ue_webgl_fluid_simulation_bg_addon10695')\n     \n    function initSmoker(canvas){\n      \/\/ canvas.parentElement.style.zIndex = 1\n      \n      const fluidOptions = {\n        TRIGGER: 'hover',\n        IMMEDIATE: false,\n        SPLAT_RADIUS: 0.084,\n        BLOOM: true,\n        SUNRAYS: true,\n        COLORFUL:  false ,\n        CUSTOM_COLOR:  true ,\n        COLOR: '#429CD1',\n        TEXTURE: 'http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/ac_assets\/ue_webgl_fluid_simulation\/img\/dithering_texture.png'\n      }\n\n      const options = {\n        canvas: canvas,\n        eventsContainer:  canvas.parentElement.parentElement ,\n        fluidOptions: fluidOptions\n      }\n\n      import('http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/ac_assets\/ue_webgl_fluid_simulation\/js\/ue_webgl_fluid.js')\n        .then( module => {\n          new module.UeWebglFluid(options)\n        })\n        .catch( error => { console.log('unable to load UeWebglFluid', error) })\n   } \n   \n   if(canvas == null){\n     setTimeout(function(){\n       const canvas = document.querySelector('#uc_ue_webgl_fluid_simulation_bg_addon10695')\n       initSmoker(canvas);\n     },300);\n   }else{\n     initSmoker(canvas);\n   }                                                                        \n                                                       \n                                                        \n})();\n<\/script>\n<!-- end Smoke Background Effect -->\t\t\t<\/template>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"elementor-element elementor-element-209c0d2b e-con-full e-flex e-con e-parent\" data-id=\"209c0d2b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4506b0a e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"4506b0a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed665a2 elementor-widget elementor-widget-spacer\" data-id=\"7ed665a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14529a7a e-con-full e-flex e-con e-child\" data-id=\"14529a7a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1b67b6eb e-flex e-con-boxed e-con e-child\" data-id=\"1b67b6eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f320562 elementor-widget elementor-widget-heading\" data-id=\"f320562\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'Offerta completa Excol:<b> Il valore del tuo investimento<\/b>\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bd7dfe5 elementor-widget elementor-widget-text-editor\" data-id=\"7bd7dfe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Il valore<\/b> del tuo diploma, in un investimento accessibile: <br \/><b>Solo 166\u20ac\/mese<\/b> (equivalente a 1990\u20ac una tantum).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12018154 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"12018154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accesso completo al<b> Metodo 6 Ore\u2122<\/b> e a tutte le sue fasi.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Iscrizione garantita <\/b>presso il nostro istituto paritario riconosciuto MIUR.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Pianificazione e organizzazione delle 4 trasferte <\/b>per gli esami di idoneit\u00e0 e l'esame di Stato finale.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Lezioni online live <\/b>con i migliori docenti e registrazioni illimitate.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Tutoraggio individuale <\/b>1-1 per un supporto personalizzato e continuo (Valore: 100\u20ac\/h, qui lo hai incluso!).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accesso esclusivo al <b>gruppo Telegram<\/b> della nostra community per confronto e motivazione (Valore: 300\u20ac, qui lo hai incluso!).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Materiali didattici<\/b> completi e aggiornati.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Garanzia \"Promosso o Ripreparato\"<\/b>: la tua serenit\u00e0 non ha prezzo, noi la garantiamo.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b2dca15 elementor-widget elementor-widget-icon-box\" data-id=\"3b2dca15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCosa ci guadagni dal tuo Diploma\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUn investimento che si ripaga da s\u00e9: un diploma di Stato pu\u00f2 aumentare il tuo potenziale di guadagno di 400\u20ac\/mese e aprirti porte a concorsi e nuove carriere.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61c258fe e-con-full e-flex e-con e-child\" data-id=\"61c258fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a702e elementor-widget elementor-widget-ucaddon_multi_line_button\" data-id=\"481a702e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_multi_line_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Multi Line Button -->\n\n<style>\/* widget: Multi Line Button *\/\n\n#uc_multi_line_button_elementor_481a702e *{\n\tmargin:0;\n\tbox-sizing: border-box;\n}\n\n#uc_multi_line_button_elementor_481a702e .uc_container_holder{\n\tposition:relative;\n\ttext-align:center;\n}\n\n#uc_multi_line_button_elementor_481a702e .uc_container_holder a.uc_multi-line-button{\n  color: white;\n  display: block;\n  text-decoration: none;\n  transition:0.3s;\n  text-align:center;\n }\n\n\n#uc_multi_line_button_elementor_481a702e .uc_container_holder a.uc_multi-line-button .uc_title {\n  \n  display: block;\n}\n\n#uc_multi_line_button_elementor_481a702e .uc_flex\n{\n  display:inline-flex;\n}\n\n.uc_title\n{\n  font-size: 24px;\n}\n\n#uc_multi_line_button_elementor_481a702e .uc_icon\n{\n  line-height:1em;\n  display:flex;\n}\n\n#uc_multi_line_button_elementor_481a702e .uc_icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n<\/style>\n\n<div class=\"uc_multi_line_buttons\" id=\"uc_multi_line_button_elementor_481a702e\">\n    \t<div class=\"uc_container_holder\">\n            <a id=\"\" class=\"uc_multi-line-button  elementor-animation-grow\" href=\"\" >\n\t\t\t\t<div class=\"uc_flex\">   \n                  \n                  \n                    \t\n\n                   \n                   \n                   <div>\n                   <div class=\"uc_title\">ISCRIVITI&#x20;ORA<\/div>\n                     <div class=\"uc_space_between\"><\/div>\n                   <span class=\"uc_subtitle\">Offerta&#x20;valida&#x20;fino&#x20;a&#x20;esaurimento&#x20;posti<\/span>\n                   <\/div>\n                  \n                  \n                  \n                <\/div>\n            <\/a>\n        <\/div>\n    <\/div>\n<!-- end Multi Line Button -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a50453d elementor-widget elementor-widget-text-editor\" data-id=\"a50453d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Possibilit\u00e0 di pagamento a rate<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34818d43 e-flex e-con-boxed e-con e-parent\" data-id=\"34818d43\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-88d33a2 e-con-full e-flex e-con e-child\" data-id=\"88d33a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2723db71 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2723db71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le storie di chi ce l'ha fatta: questa \u00e8 la prova che \u00e8 possibile\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b8f78d0 e-con-full e-flex e-con e-child\" data-id=\"1b8f78d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-446f10c9 animated-slow elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"446f10c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><p class=\"p1\"><b>Il pezzo di carta che mi mancava\u2026 e che ora mi ha cambiato la vita<\/b><\/p><p class=\"p1\">Ero bloccato. Ogni offerta di lavoro chiedeva il diploma, e io non lo avevo mai preso. Grazie al sondaggio gratuito di Excol ho scoperto un modo semplice per rimettermi in gioco. Il metodo delle 6 ore \u00e8 veramente adatto a chi lavora e ha poco tempo. Non \u00e8 stato facile, ma la garanzia \u201cPromosso o Ripreparato\u201d mi ha dato la sicurezza che mi serviva per non mollare.<\/p><p class=\"p1\"><b>Marco L., 31 anni<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b16f140 animated-slow elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2b16f140\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><p class=\"p1\"><b>Volevo dare l\u2019esempio a mio figlio. Ora posso farlo<\/b><\/p><p class=\"p1\">Dopo aver lasciato la scuola tanti anni fa, non pensavo che avrei avuto il coraggio di ricominciare. Ma quando mio figlio mi ha chiesto perch\u00e9 non avevo il diploma, ho capito che era il momento. Excol mi ha accompagnata passo dopo passo, con lezioni online che potevo seguire anche mentre gestivo la casa e la famiglia. Oggi ho finalmente il mio diploma e ne vado fiera.<i><\/i><\/p><p class=\"p1\"><b>Daniela R., 38 anni<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f4ca0ba animated-slow elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2f4ca0ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><p class=\"p1\"><b>Pensavo fosse troppo tardi per me, invece mi sbagliavo.<\/b><\/p><p>Mi chiamo Stefano, ho 43 anni e lavoro a turni. Avevo abbandonato le superiori a 17 anni, e l\u2019idea di rimettermi a studiare mi spaventava. Con Excol ho trovato un metodo pratico, flessibile e davvero personalizzato. Ho studiato da casa, seguendo 6 ore a settimana, e grazie al supporto continuo non mi sono mai sentito solo. Oggi ho il diploma in mano e sto concorrendo per un nuovo ruolo interno in azienda.<\/p><p><i><span style=\"font-weight: 400;\"><br \/><\/span><\/i><span style=\"font-weight: 400;\">\u00a0<strong>Stefano G. &#8211; 43 anni\u00a0<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6068315b e-con-full e-flex e-con e-child\" data-id=\"6068315b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39110dba elementor-widget elementor-widget-ucaddon_multi_line_button\" data-id=\"39110dba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_multi_line_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Multi Line Button -->\n\n<style>\/* widget: Multi Line Button *\/\n\n#uc_multi_line_button_elementor_39110dba *{\n\tmargin:0;\n\tbox-sizing: border-box;\n}\n\n#uc_multi_line_button_elementor_39110dba .uc_container_holder{\n\tposition:relative;\n\ttext-align:center;\n}\n\n#uc_multi_line_button_elementor_39110dba .uc_container_holder a.uc_multi-line-button{\n  color: white;\n  display: block;\n  text-decoration: none;\n  transition:0.3s;\n  text-align:center;\n }\n\n\n#uc_multi_line_button_elementor_39110dba .uc_container_holder a.uc_multi-line-button .uc_title {\n  \n  display: block;\n}\n\n#uc_multi_line_button_elementor_39110dba .uc_flex\n{\n  display:inline-flex;\n}\n\n.uc_title\n{\n  font-size: 24px;\n}\n\n#uc_multi_line_button_elementor_39110dba .uc_icon\n{\n  line-height:1em;\n  display:flex;\n}\n\n#uc_multi_line_button_elementor_39110dba .uc_icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n<\/style>\n\n<div class=\"uc_multi_line_buttons\" id=\"uc_multi_line_button_elementor_39110dba\">\n    \t<div class=\"uc_container_holder\">\n            <a id=\"\" class=\"uc_multi-line-button  elementor-animation-grow\" href=\"\" >\n\t\t\t\t<div class=\"uc_flex\">   \n                  \n                  \n                    \t\n\n                   \n                   \n                   <div>\n                   <div class=\"uc_title\">ISCRIVITI&#x20;ORA<\/div>\n                     <div class=\"uc_space_between\"><\/div>\n                   <span class=\"uc_subtitle\">Offerta&#x20;valida&#x20;fino&#x20;a&#x20;esaurimento&#x20;posti<\/span>\n                   <\/div>\n                  \n                  \n                  \n                <\/div>\n            <\/a>\n        <\/div>\n    <\/div>\n<!-- end Multi Line Button -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44b67e06 elementor-widget elementor-widget-text-editor\" data-id=\"44b67e06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Possibilit\u00e0 di pagamento a rate<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f2e77a8 e-flex e-con-boxed e-con e-parent\" data-id=\"7f2e77a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7c34ad15 e-con-full e-flex e-con e-child\" data-id=\"7c34ad15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e45df8f elementor-widget elementor-widget-heading\" data-id=\"2e45df8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>DOMANDE FREQUENTI\n<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58100e2c elementor-widget elementor-widget-n-accordion\" data-id=\"58100e2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1470\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1470\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Come si concilia lo studio con i miei turni di lavoro o i miei impegni? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1470\" class=\"elementor-element elementor-element-187d03c1 e-con-full e-flex e-con e-child\" data-id=\"187d03c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c3ec40e elementor-widget elementor-widget-text-editor\" data-id=\"7c3ec40e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Capiamo che la tua vita \u00e8 piena di impegni. \u00c8 per questo che abbiamo creato il <\/span><b>Metodo 6 Ore\u2122<\/b><span style=\"font-weight: 400;\">, progettato per la massima flessibilit\u00e0. Le nostre lezioni sono online, sia in diretta che registrate. Questo significa che puoi studiare quando hai tempo: la mattina presto, durante la pausa pranzo, la sera dopo cena o nei tuoi giorni liberi. <\/span><b>Non ci sono orari fissi da rispettare ogni giorno<\/b><span style=\"font-weight: 400;\">. Il Metodo 6 Ore\u2122 si adatta alla TUA routine, non il contrario, permettendoti di dedicare <\/span><b>solo 6 ore a settimana<\/b><span style=\"font-weight: 400;\"> al tuo percorso per <\/span><b>assorbire tutte le informazioni necessarie.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1471\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1471\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Sono troppo in l\u00e0 con gli anni \/ sono uscito da troppo tempo dalla scuola. Riuscir\u00f2? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1471\" class=\"elementor-element elementor-element-15244282 e-con-full e-flex e-con e-child\" data-id=\"15244282\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1186f10e elementor-widget elementor-widget-text-editor\" data-id=\"1186f10e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Assolutamente s\u00ec! L&#8217;et\u00e0 non \u00e8 un limite per Excol, anzi: molti dei nostri studenti hanno 30, 40 o anche 50 anni e avevano interrotto gli studi da tempo. La nostra forza \u00e8 il <\/span><b>supporto personalizzato: il Tailor Plan\u2122<\/b><span style=\"font-weight: 400;\"> adatta il programma alle tue conoscenze pregresse e il <\/span><b>tutor 1-1<\/b><span style=\"font-weight: 400;\"> ti segue passo dopo passo, colmando eventuali lacune. Abbiamo visto tantissime storie di successo di persone che, come te, pensavano fosse impossibile e invece hanno ottenuto il loro diploma con ottimi risultati. <\/span><b>Non sarai mai solo in questo percorso.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1472\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1472\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Qual \u00e8 l'impegno in presenza? Quanto \u00e8 l'impegno totale? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1472\" class=\"elementor-element elementor-element-26de9606 e-con-full e-flex e-con e-child\" data-id=\"26de9606\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55d96002 elementor-widget elementor-widget-text-editor\" data-id=\"55d96002\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L&#8217;impegno di studio principale \u00e8 online e flessibile <\/span><b>(6 ore a settimana)<\/b><span style=\"font-weight: 400;\">, come spiegato. <\/span><b>L&#8217;impegno in presenza \u00e8 limitato<\/b><span style=\"font-weight: 400;\"> e fondamentale per la validit\u00e0 legale del tuo diploma. Prevede <\/span><b>4 trasferte<\/b><span style=\"font-weight: 400;\"> organizzate dalla scuola:<\/span><\/p><p>\u00a0<\/p><ol><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Un incontro iniziale per conoscerti e definire al meglio il tuo percorso.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Un esame di idoneit\u00e0 per accedere all&#8217;ultimo anno.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Un esame di ammissione all&#8217;esame di Stato (se richiesto).<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L&#8217;Esame di Stato finale per il conseguimento del diploma. Ci occupiamo noi dell&#8217;organizzazione di queste trasferte presso la sede dell&#8217;Istituto Paritario partner, rendendo tutto pi\u00f9 semplice per te.<\/span><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1473\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1473\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cosa succede se non riesco a prepararmi per una sessione d'esame?\" <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1473\" class=\"elementor-element elementor-element-77833af e-con-full e-flex e-con e-child\" data-id=\"77833af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32624068 elementor-widget elementor-widget-text-editor\" data-id=\"32624068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Con Excol, la tua serenit\u00e0 \u00e8 una priorit\u00e0. Se per qualsiasi motivo non ti senti pronto per una sessione d&#8217;esame, o se purtroppo non dovessi superarlo al primo tentativo, entra in gioco la nostra<\/span><b> Garanzia &#8220;Promosso o Ripreparato&#8221;<\/b><span style=\"font-weight: 400;\">. Questo significa che ti prepareremo di nuovo <\/span><b>senza alcun costo aggiuntivo.<\/b><span style=\"font-weight: 400;\"> Avrai tutto il supporto necessario per ripassare e presentarti con maggiore sicurezza alla sessione successiva, senza perdere denaro o tempo. Il nostro obiettivo \u00e8 il tuo successo, non il fallimento.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1474\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1474\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quali sono le differenze tra il vostro diploma e quello del serale? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1474\" class=\"elementor-element elementor-element-4fe51620 e-con-full e-flex e-con e-child\" data-id=\"4fe51620\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e00177a elementor-widget elementor-widget-text-editor\" data-id=\"5e00177a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La differenza principale sta nella flessibilit\u00e0 e nel supporto personalizzato.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Flessibilit\u00e0<\/b><span style=\"font-weight: 400;\">: Il diploma serale richiede spesso la frequenza obbligatoria e fissa in presenza per molte ore settimanali. Con Excol, hai lezioni online (live e registrate) e un programma che si adatta ai tuoi tempi, richiedendo solo 6 ore a settimana.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Supporto e Metodo<\/b><span style=\"font-weight: 400;\">: Il nostro Metodo 6 Ore\u2122 \u00e8 studiato per l&#8217;apprendimento degli adulti, con un piano didattico su misura, tutor dedicati e checkpoint costanti. Non sei un numero, ma una persona con esigenze specifiche.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Validit\u00e0:<\/b><span style=\"font-weight: 400;\"> Entrambi i percorsi portano a un Diploma di Stato riconosciuto dal MIUR, ma con Excol lo ottieni con un approccio moderno, pi\u00f9 efficiente e adatto al tuo stile di vita.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1475\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1475\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Posso accedere a concorsi pubblici o all'universit\u00e0 con questo diploma? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1475\" class=\"elementor-element elementor-element-1af6e019 e-con-full e-flex e-con e-child\" data-id=\"1af6e019\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-735cf2cb elementor-widget elementor-widget-text-editor\" data-id=\"735cf2cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">S\u00ec, assolutamente! Il diploma che otterrai con Excol \u00e8 un <\/span><b>Diploma di Stato riconosciuto dal MIUR<\/b><span style=\"font-weight: 400;\"> (Ministero dell&#8217;Istruzione e del Merito), rilasciato da un istituto paritario. Ha la stessa identica <\/span><b>validit\u00e0 legale<\/b><span style=\"font-weight: 400;\"> di un diploma conseguito in qualsiasi scuola superiore italiana. Questo significa che <\/span><b>ti apre le porte<\/b><span style=\"font-weight: 400;\"> a:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Qualsiasi concorso pubblico che richieda il diploma di maturit\u00e0.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L&#8217;iscrizione a qualsiasi facolt\u00e0 universitaria.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L&#8217;accesso a corsi ITS e percorsi di formazione superiore.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Nuove e migliori opportunit\u00e0 nel mondo del lavoro.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e26770 e-con-full e-flex e-con e-child\" data-id=\"2e26770\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60233d5c elementor-widget elementor-widget-ucaddon_multi_line_button\" data-id=\"60233d5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_multi_line_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Multi Line Button -->\n\n<style>\/* widget: Multi Line Button *\/\n\n#uc_multi_line_button_elementor_60233d5c *{\n\tmargin:0;\n\tbox-sizing: border-box;\n}\n\n#uc_multi_line_button_elementor_60233d5c .uc_container_holder{\n\tposition:relative;\n\ttext-align:center;\n}\n\n#uc_multi_line_button_elementor_60233d5c .uc_container_holder a.uc_multi-line-button{\n  color: white;\n  display: block;\n  text-decoration: none;\n  transition:0.3s;\n  text-align:center;\n }\n\n\n#uc_multi_line_button_elementor_60233d5c .uc_container_holder a.uc_multi-line-button .uc_title {\n  \n  display: block;\n}\n\n#uc_multi_line_button_elementor_60233d5c .uc_flex\n{\n  display:inline-flex;\n}\n\n.uc_title\n{\n  font-size: 24px;\n}\n\n#uc_multi_line_button_elementor_60233d5c .uc_icon\n{\n  line-height:1em;\n  display:flex;\n}\n\n#uc_multi_line_button_elementor_60233d5c .uc_icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n<\/style>\n\n<div class=\"uc_multi_line_buttons\" id=\"uc_multi_line_button_elementor_60233d5c\">\n    \t<div class=\"uc_container_holder\">\n            <a id=\"\" class=\"uc_multi-line-button  elementor-animation-grow\" href=\"\" >\n\t\t\t\t<div class=\"uc_flex\">   \n                  \n                  \n                    \t\n\n                   \n                   \n                   <div>\n                   <div class=\"uc_title\">PARLA&#x20;CON&#x20;UN&#x20;NOSTRO&#x20;TUTOR&#x20;<\/div>\n                     <div class=\"uc_space_between\"><\/div>\n                   <span class=\"uc_subtitle\">Offerta&#x20;valida&#x20;fino&#x20;a&#x20;esaurimento&#x20;posti<\/span>\n                   <\/div>\n                  \n                  \n                  \n                <\/div>\n            <\/a>\n        <\/div>\n    <\/div>\n<!-- end Multi Line Button -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e66f436 elementor-widget elementor-widget-text-editor\" data-id=\"4e66f436\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Possibilit\u00e0 di pagamento a rate<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49f05e09 e-flex e-con-boxed e-con e-parent\" data-id=\"49f05e09\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c634ea1 elementor-widget elementor-widget-image\" data-id=\"c634ea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"200\" src=\"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png\" class=\"attachment-large size-large wp-image-165\" alt=\"\" srcset=\"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png 600w, http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz-300x100.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ed35e4f elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3ed35e4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centro Studi Excol<sup>\u00ae<\/sup>\u00a0SEDE DI UDINE: Via T. Ciconi, 22<\/p><p>P.Iva: 01780280309\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Senza diploma di maturit\u00e0, sei tagliato fuori\u2026 ma con Excol puoi farcela! Il tuo Diploma di Stato \u00e8 a portata di mano con Excol Con la flessibilit\u00e0 che desideri e la garanzia che meriti, grazie alla formula \u201cPromosso o Ripreparato\u201d https:\/\/www.youtube.com\/watch?v=XHOmBV4js_E PARLA&#x20;CON&#x20;UN&#x20;NOSTRO&#x20;TUTOR&#x20; Offerta&#x20;valida&#x20;fino&#x20;a&#x20;esaurimento&#x20;posti Possibilit\u00e0 di pagamento a rate https:\/\/www.youtube.com\/watch?v=XHOmBV4js_E L&#8217;Offerta completa Excol: Il valore del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-219","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Landing VSL - Il tuo diploma online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landing VSL - Il tuo diploma online\" \/>\n<meta property=\"og:description\" content=\"Senza diploma di maturit\u00e0, sei tagliato fuori\u2026 ma con Excol puoi farcela! Il tuo Diploma di Stato \u00e8 a portata di mano con Excol Con la flessibilit\u00e0 che desideri e la garanzia che meriti, grazie alla formula \u201cPromosso o Ripreparato\u201d https:\/\/www.youtube.com\/watch?v=XHOmBV4js_E PARLA&#x20;CON&#x20;UN&#x20;NOSTRO&#x20;TUTOR&#x20; Offerta&#x20;valida&#x20;fino&#x20;a&#x20;esaurimento&#x20;posti Possibilit\u00e0 di pagamento a rate https:\/\/www.youtube.com\/watch?v=XHOmBV4js_E L&#8217;Offerta completa Excol: Il valore del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Il tuo diploma online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T11:03:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/index.php\\\/landing-vsl-2\\\/\",\"url\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/index.php\\\/landing-vsl-2\\\/\",\"name\":\"Landing VSL - Il tuo diploma online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/index.php\\\/landing-vsl-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/index.php\\\/landing-vsl-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.iltuodiplomaonline.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/szsz.png\",\"datePublished\":\"2025-07-15T10:16:33+00:00\",\"dateModified\":\"2025-07-17T11:03:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/index.php\\\/landing-vsl-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/index.php\\\/landing-vsl-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/index.php\\\/landing-vsl-2\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.iltuodiplomaonline.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/szsz.png\",\"contentUrl\":\"http:\\\/\\\/www.iltuodiplomaonline.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/szsz.png\",\"width\":600,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/index.php\\\/landing-vsl-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landing VSL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/#website\",\"url\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/\",\"name\":\"Il tuo diploma online\",\"description\":\"Se vuoi raggiungere l'obiettivo diploma, ma lavori o non hai tempo di seguire un percorso tradizionale, Il Tuo Diploma Online &egrave; la scelta giusta!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/#organization\",\"name\":\"Centro Studi Excol\",\"url\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.iltuodiplomaonline.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-iltuodiplomaonline.png\",\"contentUrl\":\"http:\\\/\\\/www.iltuodiplomaonline.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-iltuodiplomaonline.png\",\"width\":531,\"height\":104,\"caption\":\"Centro Studi Excol\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iltuodiplomaonline.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landing VSL - Il tuo diploma online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/","og_locale":"it_IT","og_type":"article","og_title":"Landing VSL - Il tuo diploma online","og_description":"Senza diploma di maturit\u00e0, sei tagliato fuori\u2026 ma con Excol puoi farcela! Il tuo Diploma di Stato \u00e8 a portata di mano con Excol Con la flessibilit\u00e0 che desideri e la garanzia che meriti, grazie alla formula \u201cPromosso o Ripreparato\u201d https:\/\/www.youtube.com\/watch?v=XHOmBV4js_E PARLA&#x20;CON&#x20;UN&#x20;NOSTRO&#x20;TUTOR&#x20; Offerta&#x20;valida&#x20;fino&#x20;a&#x20;esaurimento&#x20;posti Possibilit\u00e0 di pagamento a rate https:\/\/www.youtube.com\/watch?v=XHOmBV4js_E L&#8217;Offerta completa Excol: Il valore del [&hellip;]","og_url":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/","og_site_name":"Il tuo diploma online","article_modified_time":"2025-07-17T11:03:19+00:00","og_image":[{"url":"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/","url":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/","name":"Landing VSL - Il tuo diploma online","isPartOf":{"@id":"https:\/\/www.iltuodiplomaonline.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/#primaryimage"},"image":{"@id":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/#primaryimage"},"thumbnailUrl":"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png","datePublished":"2025-07-15T10:16:33+00:00","dateModified":"2025-07-17T11:03:19+00:00","breadcrumb":{"@id":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/#primaryimage","url":"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png","contentUrl":"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2025\/07\/szsz.png","width":600,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.iltuodiplomaonline.it\/index.php\/landing-vsl-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iltuodiplomaonline.it\/"},{"@type":"ListItem","position":2,"name":"Landing VSL"}]},{"@type":"WebSite","@id":"https:\/\/www.iltuodiplomaonline.it\/#website","url":"https:\/\/www.iltuodiplomaonline.it\/","name":"Il tuo diploma online","description":"Se vuoi raggiungere l'obiettivo diploma, ma lavori o non hai tempo di seguire un percorso tradizionale, Il Tuo Diploma Online &egrave; la scelta giusta!","publisher":{"@id":"https:\/\/www.iltuodiplomaonline.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iltuodiplomaonline.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.iltuodiplomaonline.it\/#organization","name":"Centro Studi Excol","url":"https:\/\/www.iltuodiplomaonline.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.iltuodiplomaonline.it\/#\/schema\/logo\/image\/","url":"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2024\/06\/logo-iltuodiplomaonline.png","contentUrl":"http:\/\/www.iltuodiplomaonline.it\/wp-content\/uploads\/2024\/06\/logo-iltuodiplomaonline.png","width":531,"height":104,"caption":"Centro Studi Excol"},"image":{"@id":"https:\/\/www.iltuodiplomaonline.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/www.iltuodiplomaonline.it\/index.php\/wp-json\/wp\/v2\/pages\/219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.iltuodiplomaonline.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.iltuodiplomaonline.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.iltuodiplomaonline.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.iltuodiplomaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=219"}],"version-history":[{"count":56,"href":"http:\/\/www.iltuodiplomaonline.it\/index.php\/wp-json\/wp\/v2\/pages\/219\/revisions"}],"predecessor-version":[{"id":309,"href":"http:\/\/www.iltuodiplomaonline.it\/index.php\/wp-json\/wp\/v2\/pages\/219\/revisions\/309"}],"wp:attachment":[{"href":"http:\/\/www.iltuodiplomaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}